{"id":16151,"date":"2025-06-18T12:15:35","date_gmt":"2025-06-18T10:15:35","guid":{"rendered":"https:\/\/arrontesybarrera.com\/creatibo\/?p=16151"},"modified":"2025-06-18T13:05:55","modified_gmt":"2025-06-18T11:05:55","slug":"los-grandes-tambien-tropiezan","status":"publish","type":"post","link":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/","title":{"rendered":"Los grandes tambi\u00e9n tropiezan"},"content":{"rendered":"<div style=\"margin-top: 0px; margin-bottom: 0px;\" class=\"sharethis-inline-share-buttons\" ><\/div>\n<p>Incluso las marcas ic\u00f3nicas pueden cometer <strong>errores de branding<\/strong>. Decisiones arriesgadas, uso de nuevas tecnolog\u00edas o campa\u00f1as que no logran conectar con la audiencia pueden hacer tambalear tu reputaci\u00f3n. Nadie est\u00e1 exento de <strong>fallos<\/strong> pero podemos aprender de ellos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pol\u00e9mica no es igual al error<\/h2>\n\n\n\n<p>Antes de nada, conviene hacer una distinci\u00f3n importante:&nbsp;<strong>no todo lo pol\u00e9mico es necesariamente un error<\/strong>. Algunas campa\u00f1as buscan deliberadamente generar conversaci\u00f3n como parte de su estrategia de marca (y lo logran).&nbsp;<\/p>\n\n\n\n<p>Otras veces, en cambio, la controversia es involuntaria y las marcas pueden aprovecharla a su favor. Esto es lo que sucedi\u00f3, por ejemplo, con el cartel de&nbsp;<strong><em>Wicked<\/em><\/strong>&nbsp;y las r\u00e9plicas al cartel hechas por los fans. La respuesta de la actriz y de la propia marca no se hicieron esperar y consiguieron llamar poderosamente la atenci\u00f3n. Lo mejor es que toda esta repercusi\u00f3n no afect\u00f3 negativamente al estreno, sino todo lo contrario.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-tiktok wp-block-embed-tiktok\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"tiktok-embed\" cite=\"https:\/\/www.tiktok.com\/@sowick1329\/video\/7446774751927799072\" data-video-id=\"7446774751927799072\" data-embed-from=\"oembed\" style=\"max-width:605px; min-width:325px;\"> <section> <a target=\"_blank\" title=\"@sowick1329\" href=\"https:\/\/www.tiktok.com\/@sowick1329?refer=embed\">@sowick1329<\/a> <p>La pol\u00e9mica del cartel de <a title=\"wicked\" target=\"_blank\" href=\"https:\/\/www.tiktok.com\/tag\/wicked?refer=embed\">#Wicked<\/a><\/p> <a target=\"_blank\" title=\"\u266c sonido original - \u00c1lex Sowick - \u00c1lex Sowick\" href=\"https:\/\/www.tiktok.com\/music\/sonido-original-\u00c1lex-Sowick-7446774822476679968?refer=embed\">\u266c sonido original &#8211; \u00c1lex Sowick &#8211; \u00c1lex Sowick<\/a> <\/section> <\/blockquote> <script async src=\"https:\/\/www.tiktok.com\/embed.js\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfErrores de branding o estrategia de marca?<\/h2>\n\n\n\n<p>En todo caso, cuando las marcas cruzan la l\u00ednea que marcan sus propios valores, hieren sensibilidades clave o entran en contradicci\u00f3n consigo mismas, se produce un gran da\u00f1o a la marca, que puede llegar a ser irreparable si no se sabe resolver a tiempo. Aqu\u00ed tenemos algunos ejemplos memorables de marcas que cometieron errores:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">1. Cuando Coca-Cola \u00abdej\u00f3 de ser aut\u00e9ntica\u00bb<\/h2>\n\n\n\n<p>Aunque parezca mentira, una marca tan consolidada como Coca-Cola hizo una campa\u00f1a muy alejada de todo a lo que nos ten\u00eda acostumbrados. Intent\u00f3 ser una de las primeras marcas globales en incorporar generaci\u00f3n de video por IA, pero eso le trajo consecuencias. Esa campa\u00f1a navide\u00f1a les gener\u00f3 titulares y les asegur\u00f3 una gran cobertura medi\u00e1tica\u2026 pero no por las razones correctas, sino como uno de los errores de branding m\u00e1s sonados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"900\" height=\"505\" src=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-12.43.14.png\" alt=\"\" class=\"wp-image-16153\" srcset=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-12.43.14.png 900w, https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-12.43.14-267x150.png 267w, https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-12.43.14-768x431.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El spot, lleno de errores visuales y con un estilo visual inconsistente, termin\u00f3 por parecer amateur. Incluso el logotipo de <strong>Coca-Cola<\/strong> se deform\u00f3 en el anuncio. Entonces, \u00bfqu\u00e9 diferenciaba a <strong>Coca-Cola <\/strong>de los gen\u00e9ricos si ya no le importaba ni su propia marca?<\/li>\n\n\n\n<li>El uso de IA fue duramente criticado por consumidores que rechazan esta tecnolog\u00eda, y algunos incluso llamaron al boicot.<\/li>\n\n\n\n<li>Pero lo peor de todo, con diferencia es que el concepto de \u201cinteligencia artificial\u201d choc\u00f3 frontalmente e incluso contradijo el posicionamiento hist\u00f3rico de la marca en torno a la&nbsp;<strong>autenticidad<\/strong>, como en los slogans <strong>\u201cIt\u2019s the Real Thing\u201d<\/strong> o <strong>\u201cMagia aut\u00e9ntica\u201d<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p>Al final, lo que pudo ser una apuesta innovadora se convirti\u00f3 en una amenaza a su identidad de marca, que hab\u00eda sido concienzudamente construida durante d\u00e9cadas.&nbsp;Adem\u00e1s, al usar IA, la marca se expuso a ser v\u00edctima de imitaciones y burlas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">2. Spotify:&nbsp;De l\u00edder en streaming a caos de contenido<\/h2>\n\n\n\n<p>Spotify transform\u00f3 la forma en que escuchamos m\u00fasica, pero en 2024 sus decisiones estrat\u00e9gicas generaron confusi\u00f3n (y descontento):<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Su intento por competir con <strong>YouTube<\/strong> mediante la inclusi\u00f3n de poscast y contenido en v\u00eddeo se vio empa\u00f1ado por pol\u00e9micas como la aparici\u00f3n de pornograf\u00eda en b\u00fasquedas.<\/li>\n\n\n\n<li>Cambios dr\u00e1sticos en la interfaz y el uso de avatares de IA en campa\u00f1as como&nbsp;<em><strong>Spotify Wrapped<\/strong><\/em>&nbsp;alejaron a usuarios fieles.<\/li>\n\n\n\n<li>Lo peor de todo fueron las cr\u00edticas \u00e9ticas por intentar silenciar protestas sobre el pago a artistas, tomando acciones legales contra la web activista&nbsp;<a href=\"https:\/\/translate.google.com\/website?sl=auto&amp;tl=es&amp;hl=es&amp;client=webapp&amp;u=https:\/\/www.spotifyunwrapped.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Spotify Unwrapped,<\/a>&nbsp;cuyo objetivo era denunciar lo poco que <strong>Spotify<\/strong> paga a los artistas.&nbsp;<\/li>\n<\/ul>\n\n\n\n<p>La expansi\u00f3n sin claridad de prop\u00f3sito y el alejamiento de su base creativa da\u00f1aron seriamente su imagen de marca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">3. Bumble pas\u00f3 de empoderar a ofender<\/h2>\n\n\n\n<p>Puede ser dif\u00edcil para una app de citas encontrar el tono adecuado, pero <strong>Bumble<\/strong> hab\u00eda logrado diferenciarse como una app de citas segura y emp\u00e1tica, centrada en empoderar a las mujeres. Hasta que lanz\u00f3 su pol\u00e9mica campa\u00f1a \u00abanticelibato\u00bb y se sum\u00f3 a la lista de las marcas que cometieron terribles errores de branding.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"901\" height=\"507\" src=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-10.35.59.png\" alt=\"\" class=\"wp-image-16154\" srcset=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-10.35.59.png 901w, https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-10.35.59-267x150.png 267w, https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-10.35.59-768x432.png 768w\" sizes=\"(max-width: 901px) 100vw, 901px\" \/><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li>El mensaje inclu\u00eda frases como \u201cEl voto de celibato no es la soluci\u00f3n\u201d&nbsp;y el v\u00eddeo, a una monja que se enamora de un jardinero atractivo, algo que fue ampliamente criticado por insensible.<\/li>\n\n\n\n<li>En redes sociales,&nbsp;la campa\u00f1a gener\u00f3 debate, pero&nbsp;fue acusada de atacar creencias personales y religiosas y&nbsp;destruy\u00f3 la reputaci\u00f3n de Bumble como una app de citas sensible que empoderaba a las mujeres y promov\u00eda relaciones seguras y saludables.<\/li>\n\n\n\n<li>La respuesta fue tan negativa que <strong>Bumble<\/strong> opt\u00f3 por retirar los anuncios y pedir disculpas.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"449\" height=\"254\" src=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-17-a-las-11.50.38.png\" alt=\"\" class=\"wp-image-16159\" srcset=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-17-a-las-11.50.38.png 449w, https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-17-a-las-11.50.38-265x150.png 265w\" sizes=\"(max-width: 449px) 100vw, 449px\" \/><\/figure>\n\n\n\n<p>Este otro caso de errores de branding ilustra c\u00f3mo una mala lectura cultural puede acabar con a\u00f1os de construcci\u00f3n de marca en solo unos d\u00edas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">4. Apple: innovaci\u00f3n que confunde<\/h2>\n\n\n\n<p>Ni siquiera Apple, maestra del marketing emocional y acostumbrada a hacer las cosas bien, se libr\u00f3 de cometer errores. Aqu\u00ed tienes dos ejemplos de c\u00f3mo un storytelling fallido puede deshumanizar una marca que siempre hab\u00eda puesto al usuario en el centro.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>El anuncio del iPad Pro en el que aplasta la creatividad<\/strong>: una pieza visual donde una prensa hidr\u00e1ulica aplasta instrumentos art\u00edsticos para demostrar lo \u201ctodo en uno\u201d del dispositivo. El mensaje fue interpretado como&nbsp;<strong>hostil hacia la creatividad humana<\/strong>. Personajes como el actor&nbsp;<strong>Hugh Grant<\/strong>&nbsp;y el director&nbsp;<strong>Reed Morano<\/strong>&nbsp;tomaron partido. El primero tuite\u00f3:&nbsp;\u00abLa destrucci\u00f3n de la experiencia humana. Cortes\u00eda de Silicon Valley\u00bb. Y el segundo replic\u00f3: \u00abESTA MIERDA ES REALMENTE PSIC\u00d3TICA.&nbsp;Un paso en falso poco com\u00fan para una marca que normalmente abraza la creatividad, pero que esta vez&nbsp;alej\u00f3 a segmentos clave de su base de clientes.&nbsp;<strong>Apple<\/strong>r\u00e1pidamente retir\u00f3 el anuncio tras las protestas.<\/li>\n\n\n\n<li><strong>Apple tambi\u00e9n ofendi\u00f3 a todo un pa\u00eds poco despu\u00e9s con su anuncio para Tailandia<\/strong>, que estaba plagado de estereotipos culturales, y desat\u00f3 indignaci\u00f3n en el pa\u00eds asi\u00e1tico. Apple tuvo que pedir disculpas y tambi\u00e9n retirar la pieza.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"512\" height=\"762\" src=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-17-a-las-11.51.55.png\" alt=\"\" class=\"wp-image-16160\" srcset=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-17-a-las-11.51.55.png 512w, https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-17-a-las-11.51.55-101x150.png 101w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">5. \u00bfY Jaguar?<\/h2>\n\n\n\n<p>Un caso m\u00e1s complejo es el de&nbsp;<strong>Jaguar<\/strong>, que sorprendi\u00f3 a todos con su rebranding radical. Aunque la reacci\u00f3n inicial fue negativa, especialmente entre su base tradicional de consumidores, todav\u00eda no est\u00e1 claro si esto seguir\u00e1 siendo un error a largo plazo o no.<\/p>\n\n\n\n<p>La marca parece estar apuntando a un nuevo p\u00fablico, m\u00e1s joven y alineado con la movilidad el\u00e9ctrica. Si logra conectar con esa audiencia, el cambio no solo no ser\u00eda un error, sino que podr\u00eda acabar resultando algo visionario.&nbsp;Solo el tiempo<strong> (<\/strong>y los pr\u00f3ximos modelos<strong>)<\/strong>&nbsp;dir\u00e1n si fue una jugada maestra o un salto al vac\u00edo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"485\" height=\"648\" src=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-12.04.50.png\" alt=\"\" class=\"wp-image-16155\" srcset=\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-12.04.50.png 485w, https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/Captura-de-pantalla-2025-06-12-a-las-12.04.50-112x150.png 112w\" sizes=\"(max-width: 485px) 100vw, 485px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 podemos aprender?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>La coherencia importa<\/strong>: Las marcas deben alinear su narrativa con sus valores. Coca-Cola y Apple lo olvidaron, y el p\u00fablico lo not\u00f3.<\/li>\n\n\n\n<li><strong>Escuchar es clave<\/strong>:&nbsp;<strong>Bumble<\/strong>&nbsp;y&nbsp;<strong>Spotify<\/strong>&nbsp;sufrieron por haber ignorado las sensibilidades de sus usuarios.<\/li>\n\n\n\n<li><strong>La innovaci\u00f3n debe ser significativa<\/strong>: El uso de la tecnolog\u00eda debe estar al servicio de una experiencia coherente y no alrev\u00e9s.<\/li>\n<\/ul>\n\n\n\n<p>Tal y como hemos visto, incluso los grandes fallan. Pero la diferencia est\u00e1 en&nbsp;<strong>c\u00f3mo responden<\/strong>, aprenden y evolucionan de sus errores de branding para seguir siendo coherentes.&nbsp;En&nbsp;<a href=\"https:\/\/arrontesybarrera.com\/\"><strong>Arron<\/strong><\/a><a href=\"https:\/\/arrontesybarrera.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>tes y Barrera<\/strong><\/a>,&nbsp;<strong>tu agencia de publicidad en Asturias<\/strong> podemos ayudarte a ser coherentes con tu marca. As\u00ed podr\u00e1s seguir d\u00e1ndoles a tus consumidores un buen motivo para comprar. Ll\u00e1manos y te asesoramos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Incluso las marcas ic\u00f3nicas pueden cometer errores de branding. Decisiones arriesgadas, uso de nuevas tecnolog\u00edas o campa\u00f1as que no logran conectar con la audiencia pueden hacer tambalear tu reputaci\u00f3n. Nadie est\u00e1 exento de fallos pero podemos aprender de ellos. Pol\u00e9mica no es igual al error Antes de nada, conviene hacer una distinci\u00f3n importante:&nbsp;no todo lo [&hellip;]<\/p>\n","protected":false},"author":17,"featured_media":16165,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[18,174,61],"class_list":["post-16151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branding","tag-branding","tag-estrategia-creativa","tag-estrategia-de-marca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los grandes tambi\u00e9n tropiezan - Creatibo<\/title>\n<meta name=\"description\" content=\"Las marcas ic\u00f3nicas pueden cometer errores de branding. Nadie est\u00e1 exento de fallos pero podemos aprender de ellos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los grandes tambi\u00e9n tropiezan - Creatibo\" \/>\n<meta property=\"og:description\" content=\"Las marcas ic\u00f3nicas pueden cometer errores de branding. Nadie est\u00e1 exento de fallos pero podemos aprender de ellos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/\" \/>\n<meta property=\"og:site_name\" content=\"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital.\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T10:15:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T11:05:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"In\u00e9s Fern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"In\u00e9s Fern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/\"},\"author\":{\"name\":\"In\u00e9s Fern\u00e1ndez\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/person\/4fffe89b8836cfa475115a52df01b426\"},\"headline\":\"Los grandes tambi\u00e9n tropiezan\",\"datePublished\":\"2025-06-18T10:15:35+00:00\",\"dateModified\":\"2025-06-18T11:05:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/\"},\"wordCount\":1298,\"publisher\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#organization\"},\"image\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg\",\"keywords\":[\"branding\",\"estrategia creativa\",\"estrategia de marca\"],\"articleSection\":[\"Branding\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/\",\"url\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/\",\"name\":\"Los grandes tambi\u00e9n tropiezan - Creatibo\",\"isPartOf\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg\",\"datePublished\":\"2025-06-18T10:15:35+00:00\",\"dateModified\":\"2025-06-18T11:05:55+00:00\",\"description\":\"Las marcas ic\u00f3nicas pueden cometer errores de branding. Nadie est\u00e1 exento de fallos pero podemos aprender de ellos.\",\"breadcrumb\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage\",\"url\":\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg\",\"contentUrl\":\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg\",\"width\":1500,\"height\":1500,\"caption\":\"Errores de branding: Los grandes tambi\u00e9n tropiezan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/arrontesybarrera.com\/creatibo\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los grandes tambi\u00e9n tropiezan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#website\",\"url\":\"https:\/\/arrontesybarrera.com\/creatibo\/\",\"name\":\"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital.\",\"description\":\"Creatibo es el blog de Arrontes y Barrera sobre creatividad para los profesionales del marketing en un mundo muy digital.\",\"publisher\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/arrontesybarrera.com\/creatibo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#organization\",\"name\":\"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital.\",\"url\":\"https:\/\/arrontesybarrera.com\/creatibo\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2022\/03\/arrontes-y-barrera-logo@2x.png\",\"contentUrl\":\"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2022\/03\/arrontes-y-barrera-logo@2x.png\",\"width\":424,\"height\":70,\"caption\":\"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital.\"},\"image\":{\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/person\/4fffe89b8836cfa475115a52df01b426\",\"name\":\"In\u00e9s Fern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3adafd4f1df0c34d8d35187c8ad4f8e0c3c7711da64cc0b2d963b6a03973f396?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3adafd4f1df0c34d8d35187c8ad4f8e0c3c7711da64cc0b2d963b6a03973f396?s=96&d=mm&r=g\",\"caption\":\"In\u00e9s Fern\u00e1ndez\"},\"url\":\"https:\/\/arrontesybarrera.com\/creatibo\/author\/inesfernandezarrontesybarrera-com\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los grandes tambi\u00e9n tropiezan - Creatibo","description":"Las marcas ic\u00f3nicas pueden cometer errores de branding. Nadie est\u00e1 exento de fallos pero podemos aprender de ellos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/","og_locale":"es_ES","og_type":"article","og_title":"Los grandes tambi\u00e9n tropiezan - Creatibo","og_description":"Las marcas ic\u00f3nicas pueden cometer errores de branding. Nadie est\u00e1 exento de fallos pero podemos aprender de ellos.","og_url":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/","og_site_name":"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital.","article_published_time":"2025-06-18T10:15:35+00:00","article_modified_time":"2025-06-18T11:05:55+00:00","og_image":[{"width":1500,"height":1500,"url":"http:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg","type":"image\/jpeg"}],"author":"In\u00e9s Fern\u00e1ndez","twitter_card":"summary_large_image","twitter_misc":{"Written by":"In\u00e9s Fern\u00e1ndez","Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#article","isPartOf":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/"},"author":{"name":"In\u00e9s Fern\u00e1ndez","@id":"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/person\/4fffe89b8836cfa475115a52df01b426"},"headline":"Los grandes tambi\u00e9n tropiezan","datePublished":"2025-06-18T10:15:35+00:00","dateModified":"2025-06-18T11:05:55+00:00","mainEntityOfPage":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/"},"wordCount":1298,"publisher":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/#organization"},"image":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage"},"thumbnailUrl":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg","keywords":["branding","estrategia creativa","estrategia de marca"],"articleSection":["Branding"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/","url":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/","name":"Los grandes tambi\u00e9n tropiezan - Creatibo","isPartOf":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage"},"image":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage"},"thumbnailUrl":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg","datePublished":"2025-06-18T10:15:35+00:00","dateModified":"2025-06-18T11:05:55+00:00","description":"Las marcas ic\u00f3nicas pueden cometer errores de branding. Nadie est\u00e1 exento de fallos pero podemos aprender de ellos.","breadcrumb":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#primaryimage","url":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg","contentUrl":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg","width":1500,"height":1500,"caption":"Errores de branding: Los grandes tambi\u00e9n tropiezan"},{"@type":"BreadcrumbList","@id":"https:\/\/arrontesybarrera.com\/creatibo\/los-grandes-tambien-tropiezan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arrontesybarrera.com\/creatibo\/"},{"@type":"ListItem","position":2,"name":"Los grandes tambi\u00e9n tropiezan"}]},{"@type":"WebSite","@id":"https:\/\/arrontesybarrera.com\/creatibo\/#website","url":"https:\/\/arrontesybarrera.com\/creatibo\/","name":"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital.","description":"Creatibo es el blog de Arrontes y Barrera sobre creatividad para los profesionales del marketing en un mundo muy digital.","publisher":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arrontesybarrera.com\/creatibo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/arrontesybarrera.com\/creatibo\/#organization","name":"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital.","url":"https:\/\/arrontesybarrera.com\/creatibo\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/logo\/image\/","url":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2022\/03\/arrontes-y-barrera-logo@2x.png","contentUrl":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2022\/03\/arrontes-y-barrera-logo@2x.png","width":424,"height":70,"caption":"Creatibo, el blog de Arrontes y Barrera. Creatividad en un mundo muy digital."},"image":{"@id":"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/person\/4fffe89b8836cfa475115a52df01b426","name":"In\u00e9s Fern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arrontesybarrera.com\/creatibo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3adafd4f1df0c34d8d35187c8ad4f8e0c3c7711da64cc0b2d963b6a03973f396?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3adafd4f1df0c34d8d35187c8ad4f8e0c3c7711da64cc0b2d963b6a03973f396?s=96&d=mm&r=g","caption":"In\u00e9s Fern\u00e1ndez"},"url":"https:\/\/arrontesybarrera.com\/creatibo\/author\/inesfernandezarrontesybarrera-com\/"}]}},"jetpack_featured_media_url":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR.jpg","featured_image_src":"https:\/\/arrontesybarrera.com\/creatibo\/wp-content\/uploads\/2025\/06\/LATA-ERROR-150x150.jpg","_links":{"self":[{"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/posts\/16151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/comments?post=16151"}],"version-history":[{"count":9,"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/posts\/16151\/revisions"}],"predecessor-version":[{"id":16167,"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/posts\/16151\/revisions\/16167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/media\/16165"}],"wp:attachment":[{"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/media?parent=16151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/categories?post=16151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arrontesybarrera.com\/creatibo\/wp-json\/wp\/v2\/tags?post=16151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}